{"id":127,"count":0,"description":"","link":"http:\/\/www.indiansaddlery.com\/blog\/tag\/kitchen-sauce-warmer-4aba-375c48\/","name":"Kitchen Sauce Warmer","slug":"kitchen-sauce-warmer-4aba-375c48","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/tags\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/posts?tags=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}