{"id":254,"count":0,"description":"","link":"http:\/\/www.indiansaddlery.com\/blog\/tag\/lose-weight-peptides-4970-d81835\/","name":"Lose Weight Peptides","slug":"lose-weight-peptides-4970-d81835","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/tags\/254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/posts?tags=254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}