{"id":275,"count":0,"description":"","link":"http:\/\/www.indiansaddlery.com\/blog\/tag\/top-view-led-neon-flex-4a99-f4051c\/","name":"Top View LED Neon Flex","slug":"top-view-led-neon-flex-4a99-f4051c","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/tags\/275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.indiansaddlery.com\/blog\/wp-json\/wp\/v2\/posts?tags=275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}